{"id":4441,"date":"2022-02-02T08:25:00","date_gmt":"2022-02-02T07:25:00","guid":{"rendered":"https:\/\/apartamentselsllacs.com\/coupe-europe-finales-ski-alpin\/"},"modified":"2022-02-02T08:25:00","modified_gmt":"2022-02-02T07:25:00","slug":"coupe-europe-finales-ski-alpin","status":"publish","type":"post","link":"https:\/\/apartamentselsllacs.com\/fr\/coupe-europe-finales-ski-alpin\/","title":{"rendered":"Les nouvelles finales de la Coupe d&rsquo;Europe de ski alpin arrivent \u00e0 Grandvalira"},"content":{"rendered":"<p>Cette ann\u00e9e, les grandes comp\u00e9titions reviennent \u00e0 Grandvalira. En mars, les finales de la Coupe d&rsquo;Europe de ski alpin seront de retour \u00e0 Grandvalira. Voici tous les d\u00e9tails, pour ne rien manquer.<\/p>\n<h2><strong>Les Finales de la Coupe d&rsquo;Europe de ski alpin <\/strong><\/h2>\n<p>Du 14 au 20 mars, l&rsquo;action se d\u00e9roule \u00e0 Grandvalira, sur les deux pistes de la Coupe du monde Avet \u00e0 Soldeu et \u00c0liga \u00e0 El Tarter. Pr\u00e9parez-vous donc \u00e0 ressentir les sensations des grands \u00e9v\u00e9nements de premi\u00e8re main. C&rsquo;est l&rsquo;occasion de voir les meilleurs skieurs d&rsquo;Europe en comp\u00e9tition en Andorre.<\/p>\n<p>Ces derni\u00e8res saisons, <strong>Grandvalira a d\u00e9j\u00e0 accueilli d&rsquo;autres comp\u00e9titions de ski alpin telles que des \u00e9preuves de la Coupe du monde, des \u00e9preuves de la Coupe d&rsquo;Europe et a accueilli les finales de la Coupe du monde<\/strong> masculine et f\u00e9minine en 2019. C&rsquo;est \u00e9galement le lieu o\u00f9 se d\u00e9roulent chaque ann\u00e9e les \u00e9preuves du Kilom\u00e8tre Lanc\u00e9 sur la piste du Riberal de Grau Roig. Et le Snow Park du secteur d&rsquo;El Tarter o\u00f9 se sont d\u00e9roul\u00e9es des comp\u00e9titions de haut niveau telles que les Total Fight Masters of Freestyle.<\/p>\n<h2><strong>Les pistes de la Coupe du monde <\/strong><\/h2>\n<p>La proximit\u00e9 d&rsquo;Els Llacs Mountain Apartments avec ces pistes en fait un bon choix pour assister aux finales de la Coupe d&rsquo;Europe de ski alpin. Situ\u00e9 \u00e0 Bordes de Envalira, la piste Avet de Soldeu est \u00e0 5 minutes en voiture et \u00e0 15 minutes de la piste \u00c0liga d&rsquo;El Tarter.<\/p>\n<h4><strong>&#8211; La piste de l&rsquo;Avet, \u00e0 Soldeu<\/strong><\/h4>\n<p>C&rsquo;est la premi\u00e8re piste \u00e0 obtenir l&rsquo;homologation de la F\u00e9d\u00e9ration internationale de ski (FIS). En 2008, Grandvalira a accueilli son premier \u00e9v\u00e9nement important de la Coupe d&rsquo;Europe. Il y a deux <strong>pistes techniques : le slalom et le G\u00e9ant.<\/strong>&nbsp;&nbsp;&nbsp;<\/p>\n<p>Gr\u00e2ce \u00e0 son orientation nord-ouest, elle garantit une excellente qualit\u00e9 de neige. \u00c0 l&rsquo;occasion de la finale de la Coupe du monde 2019, une plateforme de ski de 14 000 m\u00e8tres carr\u00e9s a \u00e9t\u00e9 construite pour relier la piste au village de Soldeu. C&rsquo;est dans cette section, qui permet d&rsquo;\u00e9tendre la zone d&rsquo;arriv\u00e9e de 100 m\u00e8tres, que se trouvent les tribunes pour les comp\u00e9titions.<\/p>\n<h4><strong>&#8211; La piste de l&rsquo;\u00c0liga, \u00e0 El Tarter<\/strong><\/h4>\n<p>Elle a accueilli son premier \u00e9v\u00e9nement majeur en 2014 avec les finales de la Coupe d&rsquo;Europe masculine et f\u00e9minine. Il s&rsquo;agit de la piste sur laquelle se d\u00e9roulent <strong>les \u00e9preuves de vitesse : descente et super g\u00e9ant.<\/strong> Elle est longue de 2,7 kilom\u00e8tres, pr\u00e9sente une pente maximale de 751 m\u00e8tres et son point de d\u00e9part le plus \u00e9lev\u00e9 se situe \u00e0 2 476 m\u00e8tres au-dessus du niveau de la mer. Gr\u00e2ce \u00e0 ces conditions, les skieurs peuvent atteindre des vitesses allant jusqu&rsquo;\u00e0 120 km\/h. De plus, c&rsquo;est la pente qui repr\u00e9sente le logo X de Grandvalira.&nbsp;<\/p>\n<h2><strong>Le programme des finales de l&rsquo;Europa Cup 2022<\/strong><\/h2>\n<p>Les finales se d\u00e9rouleront du 14 au 20 mars et accueilleront un total de 4 \u00e9preuves.<\/p>\n<p><strong>&#8211; Comp\u00e9titions sur la piste El Tarter du secteur \u00c0liga&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; <\/strong><\/p>\n<p>14\/ et 15\/03\/22 : entra\u00eenements de descente pour les femmes&nbsp;<\/p>\n<p>16\/03\/22 : Descente des femmes<\/p>\n<p>17\/03\/22 : Femmes superg\u00e9antes<\/p>\n<p>18\/03\/22 : Hommes superg\u00e9ants<\/p>\n<p>19\/03\/22 : 2 entra\u00eenements de descente pour les hommes<\/p>\n<p>20\/03\/22 : Descente des hommes<\/p>\n<p><strong>&#8211; Comp\u00e9titions sur la piste Avet secteur Soldeu<\/strong><\/p>\n<p>15\/03\/22 : Slalom g\u00e9ant hommes<\/p>\n<p>16\/03\/22 : Slalom hommes<\/p>\n<p>19\/03\/22 : Slalom g\u00e9ant f\u00e9minin<\/p>\n<p>20\/03\/22 : Slalom f\u00e9minin<\/p>\n<h2><strong>Futurs grands \u00e9v\u00e8nements \u00e0 Grandvalira <\/strong><\/h2>\n<p>On sait d\u00e9j\u00e0 <strong>qu&rsquo;une nouvelle \u00e9dition des finales de la Coupe du monde aura lieu en mars 2023<\/strong>, gr\u00e2ce au bon accueil de celles de 2019. En outre, Grandvalira a \u00e9galement pos\u00e9 sa candidature pour accueillir les Championnats du monde de ski alpin de 2027. Elle se mesure \u00e0 d&rsquo;autres grandes stations telles que Crans Montana en Suisse, Garmisch Partenkirchen (Allemagne) et Narvik (Norv\u00e8ge). La FIS annoncera le gagnant en mai de cette ann\u00e9e.<\/p>\n<p>Il est maintenant temps de profiter des finales de la Coupe d&rsquo;Europe en mars, qui sont sur le point de commencer et sont tr\u00e8s proches des Els Llacs Mountain Apartments.<\/p>\n<p>Alors si vous voulez vibrer avec l&rsquo;\u00e9v\u00e9nement sportif de l&rsquo;ann\u00e9e \u00e0 Grandvalira, <a href=\"https:\/\/apartamentselsllacs.com\/fr\/\">r\u00e9servez l&rsquo;un de nos appartements de vacances.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cette ann\u00e9e, les grandes comp\u00e9titions reviennent \u00e0 Grandvalira. En mars, les finales de la Coupe d&rsquo;Europe de ski alpin seront de retour \u00e0 Grandvalira. Voici tous les d\u00e9tails, pour ne rien manquer. Les Finales de la Coupe d&rsquo;Europe de ski alpin Du 14 au 20 mars, l&rsquo;action se d\u00e9roule \u00e0 Grandvalira, sur les deux pistes &#8230;<\/p>\n","protected":false},"author":1,"featured_media":3313,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"loftocean_post_format_gallery":"","loftocean_post_format_gallery_ids":"","loftocean_post_format_gallery_urls":"","loftocean_post_format_video_id":0,"loftocean_post_format_video_url":"","loftocean_post_format_video_type":"","loftocean_post_format_video":"","loftocean_post_format_audio_type":"","loftocean_post_format_audio_url":"","loftocean_post_format_audio_id":0,"loftocean_post_format_audio":"","loftocean-like-count":0,"cozystay_single_post_hide_site_header":"","cozystay_single_post_site_header_source":"","cozystay_single_post_custom_site_header":"0","cozystay_single_post_custom_sticky_site_header":"0","cozystay_single_post_hide_page_title":"","cozystay_single_post_site_footer_hide_main":"","cozystay_single_custom_site_footer_main_source":"","cozystay_single_custom_site_footer_main":"0","cozystay_single_post_site_footer_hide_above":"","cozystay_single_custom_site_footer_above_source":"","cozystay_single_custom_site_footer_above":"0","cozystay_single_post_site_footer_hide_instagram":"","cozystay_single_post_site_footer_hide_bottom":"","cozystay_single_custom_mobile_menu_source":"","cozystay_single_custom_mobile_menu":"0","cozystay_single_custom_mobile_menu_animation":"","cozystay_single_custom_mobile_menu_width":"","cozystay_single_custom_mobile_menu_custom_width":375,"cozystay_single_post_template":"","footnotes":""},"categories":[74,67],"tags":[],"class_list":["post-4441","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-evenements-en-andorre","category-ski-et-sports-dhiver"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les finales de la Coupe d&#039;Europe de ski arrivent en Andorre<\/title>\n<meta name=\"description\" content=\"Grandvalira accueille de nouvelles finales de la Coupe d&#039;Europe de ski alpin dans les secteurs de Soldeu et El Tarter. Cliquez ici pour en savoir plus.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/apartamentselsllacs.com\/fr\/coupe-europe-finales-ski-alpin\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les finales de la Coupe d&#039;Europe de ski arrivent en Andorre\" \/>\n<meta property=\"og:description\" content=\"Grandvalira accueille de nouvelles finales de la Coupe d&#039;Europe de ski alpin dans les secteurs de Soldeu et El Tarter. Cliquez ici pour en savoir plus.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/apartamentselsllacs.com\/fr\/coupe-europe-finales-ski-alpin\/\" \/>\n<meta property=\"og:site_name\" content=\"Apartaments Els Llacs\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/apartaments.elsllacs\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-02T07:25:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/apartamentselsllacs.com\/wp-content\/uploads\/2022\/02\/Finales-Copa-Europa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"elsllacs\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"elsllacs\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/apartamentselsllacs.com\/fr\/coupe-europe-finales-ski-alpin\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/apartamentselsllacs.com\/fr\/coupe-europe-finales-ski-alpin\/\"},\"author\":{\"name\":\"elsllacs\",\"@id\":\"https:\/\/apartamentselsllacs.com\/fr\/#\/schema\/person\/aed34ab05a7f0812d0dcebbe46f43ea5\"},\"headline\":\"Les nouvelles finales de la Coupe d&rsquo;Europe de ski alpin arrivent \u00e0 Grandvalira\",\"datePublished\":\"2022-02-02T07:25:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/apartamentselsllacs.com\/fr\/coupe-europe-finales-ski-alpin\/\"},\"wordCount\":741,\"publisher\":{\"@id\":\"https:\/\/apartamentselsllacs.com\/fr\/#organization\"},\"image\":{\"@id\":\"https:\/\/apartamentselsllacs.com\/fr\/coupe-europe-finales-ski-alpin\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/apartamentselsllacs.com\/wp-content\/uploads\/2022\/02\/Finales-Copa-Europa.jpg\",\"articleSection\":[\"\u00e9v\u00e9nements en Andorre\",\"ski et sports d'hiver\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/apartamentselsllacs.com\/fr\/coupe-europe-finales-ski-alpin\/\",\"url\":\"https:\/\/apartamentselsllacs.com\/fr\/coupe-europe-finales-ski-alpin\/\",\"name\":\"Les finales de la Coupe d'Europe de ski arrivent en Andorre\",\"isPartOf\":{\"@id\":\"https:\/\/apartamentselsllacs.com\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/apartamentselsllacs.com\/fr\/coupe-europe-finales-ski-alpin\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/apartamentselsllacs.com\/fr\/coupe-europe-finales-ski-alpin\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/apartamentselsllacs.com\/wp-content\/uploads\/2022\/02\/Finales-Copa-Europa.jpg\",\"datePublished\":\"2022-02-02T07:25:00+00:00\",\"description\":\"Grandvalira accueille de nouvelles finales de la Coupe d'Europe de ski alpin dans les secteurs de Soldeu et El Tarter. Cliquez ici pour en savoir plus.\",\"breadcrumb\":{\"@id\":\"https:\/\/apartamentselsllacs.com\/fr\/coupe-europe-finales-ski-alpin\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/apartamentselsllacs.com\/fr\/coupe-europe-finales-ski-alpin\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/apartamentselsllacs.com\/fr\/coupe-europe-finales-ski-alpin\/#primaryimage\",\"url\":\"https:\/\/apartamentselsllacs.com\/wp-content\/uploads\/2022\/02\/Finales-Copa-Europa.jpg\",\"contentUrl\":\"https:\/\/apartamentselsllacs.com\/wp-content\/uploads\/2022\/02\/Finales-Copa-Europa.jpg\",\"width\":1080,\"height\":675,\"caption\":\"Pista Avet de Soldeu\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/apartamentselsllacs.com\/fr\/coupe-europe-finales-ski-alpin\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/apartamentselsllacs.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les nouvelles finales de la Coupe d&#8217;Europe de ski alpin arrivent \u00e0 Grandvalira\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/apartamentselsllacs.com\/fr\/#website\",\"url\":\"https:\/\/apartamentselsllacs.com\/fr\/\",\"name\":\"Apartaments Els Llacs\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/apartamentselsllacs.com\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/apartamentselsllacs.com\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/apartamentselsllacs.com\/fr\/#organization\",\"name\":\"Apartaments Els Llacs\",\"url\":\"https:\/\/apartamentselsllacs.com\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/apartamentselsllacs.com\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/apartamentselsllacs.com\/wp-content\/uploads\/2025\/09\/ELS_LLACS_BORDES_COLOR_RGB-1.jpg\",\"contentUrl\":\"https:\/\/apartamentselsllacs.com\/wp-content\/uploads\/2025\/09\/ELS_LLACS_BORDES_COLOR_RGB-1.jpg\",\"width\":1478,\"height\":308,\"caption\":\"Apartaments Els Llacs\"},\"image\":{\"@id\":\"https:\/\/apartamentselsllacs.com\/fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/apartaments.elsllacs\",\"https:\/\/www.instagram.com\/elsllacs_apartaments\/\",\"https:\/\/www.youtube.com\/channel\/UCEPtRdzn0nqkij0s3IkKU0g\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/apartamentselsllacs.com\/fr\/#\/schema\/person\/aed34ab05a7f0812d0dcebbe46f43ea5\",\"name\":\"elsllacs\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/apartamentselsllacs.com\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e415adb15139330767a4113d338422f1fe2f1a98bb8c2c7d1a1a213bc5005cc8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e415adb15139330767a4113d338422f1fe2f1a98bb8c2c7d1a1a213bc5005cc8?s=96&d=mm&r=g\",\"caption\":\"elsllacs\"},\"sameAs\":[\"https:\/\/apartamentselsllacs.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les finales de la Coupe d'Europe de ski arrivent en Andorre","description":"Grandvalira accueille de nouvelles finales de la Coupe d'Europe de ski alpin dans les secteurs de Soldeu et El Tarter. Cliquez ici pour en savoir plus.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/apartamentselsllacs.com\/fr\/coupe-europe-finales-ski-alpin\/","og_locale":"fr_FR","og_type":"article","og_title":"Les finales de la Coupe d'Europe de ski arrivent en Andorre","og_description":"Grandvalira accueille de nouvelles finales de la Coupe d'Europe de ski alpin dans les secteurs de Soldeu et El Tarter. Cliquez ici pour en savoir plus.","og_url":"https:\/\/apartamentselsllacs.com\/fr\/coupe-europe-finales-ski-alpin\/","og_site_name":"Apartaments Els Llacs","article_publisher":"https:\/\/www.facebook.com\/apartaments.elsllacs","article_published_time":"2022-02-02T07:25:00+00:00","og_image":[{"width":1080,"height":675,"url":"https:\/\/apartamentselsllacs.com\/wp-content\/uploads\/2022\/02\/Finales-Copa-Europa.jpg","type":"image\/jpeg"}],"author":"elsllacs","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"elsllacs","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/apartamentselsllacs.com\/fr\/coupe-europe-finales-ski-alpin\/#article","isPartOf":{"@id":"https:\/\/apartamentselsllacs.com\/fr\/coupe-europe-finales-ski-alpin\/"},"author":{"name":"elsllacs","@id":"https:\/\/apartamentselsllacs.com\/fr\/#\/schema\/person\/aed34ab05a7f0812d0dcebbe46f43ea5"},"headline":"Les nouvelles finales de la Coupe d&rsquo;Europe de ski alpin arrivent \u00e0 Grandvalira","datePublished":"2022-02-02T07:25:00+00:00","mainEntityOfPage":{"@id":"https:\/\/apartamentselsllacs.com\/fr\/coupe-europe-finales-ski-alpin\/"},"wordCount":741,"publisher":{"@id":"https:\/\/apartamentselsllacs.com\/fr\/#organization"},"image":{"@id":"https:\/\/apartamentselsllacs.com\/fr\/coupe-europe-finales-ski-alpin\/#primaryimage"},"thumbnailUrl":"https:\/\/apartamentselsllacs.com\/wp-content\/uploads\/2022\/02\/Finales-Copa-Europa.jpg","articleSection":["\u00e9v\u00e9nements en Andorre","ski et sports d'hiver"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/apartamentselsllacs.com\/fr\/coupe-europe-finales-ski-alpin\/","url":"https:\/\/apartamentselsllacs.com\/fr\/coupe-europe-finales-ski-alpin\/","name":"Les finales de la Coupe d'Europe de ski arrivent en Andorre","isPartOf":{"@id":"https:\/\/apartamentselsllacs.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/apartamentselsllacs.com\/fr\/coupe-europe-finales-ski-alpin\/#primaryimage"},"image":{"@id":"https:\/\/apartamentselsllacs.com\/fr\/coupe-europe-finales-ski-alpin\/#primaryimage"},"thumbnailUrl":"https:\/\/apartamentselsllacs.com\/wp-content\/uploads\/2022\/02\/Finales-Copa-Europa.jpg","datePublished":"2022-02-02T07:25:00+00:00","description":"Grandvalira accueille de nouvelles finales de la Coupe d'Europe de ski alpin dans les secteurs de Soldeu et El Tarter. Cliquez ici pour en savoir plus.","breadcrumb":{"@id":"https:\/\/apartamentselsllacs.com\/fr\/coupe-europe-finales-ski-alpin\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/apartamentselsllacs.com\/fr\/coupe-europe-finales-ski-alpin\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/apartamentselsllacs.com\/fr\/coupe-europe-finales-ski-alpin\/#primaryimage","url":"https:\/\/apartamentselsllacs.com\/wp-content\/uploads\/2022\/02\/Finales-Copa-Europa.jpg","contentUrl":"https:\/\/apartamentselsllacs.com\/wp-content\/uploads\/2022\/02\/Finales-Copa-Europa.jpg","width":1080,"height":675,"caption":"Pista Avet de Soldeu"},{"@type":"BreadcrumbList","@id":"https:\/\/apartamentselsllacs.com\/fr\/coupe-europe-finales-ski-alpin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/apartamentselsllacs.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Les nouvelles finales de la Coupe d&#8217;Europe de ski alpin arrivent \u00e0 Grandvalira"}]},{"@type":"WebSite","@id":"https:\/\/apartamentselsllacs.com\/fr\/#website","url":"https:\/\/apartamentselsllacs.com\/fr\/","name":"Apartaments Els Llacs","description":"","publisher":{"@id":"https:\/\/apartamentselsllacs.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/apartamentselsllacs.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/apartamentselsllacs.com\/fr\/#organization","name":"Apartaments Els Llacs","url":"https:\/\/apartamentselsllacs.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/apartamentselsllacs.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/apartamentselsllacs.com\/wp-content\/uploads\/2025\/09\/ELS_LLACS_BORDES_COLOR_RGB-1.jpg","contentUrl":"https:\/\/apartamentselsllacs.com\/wp-content\/uploads\/2025\/09\/ELS_LLACS_BORDES_COLOR_RGB-1.jpg","width":1478,"height":308,"caption":"Apartaments Els Llacs"},"image":{"@id":"https:\/\/apartamentselsllacs.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/apartaments.elsllacs","https:\/\/www.instagram.com\/elsllacs_apartaments\/","https:\/\/www.youtube.com\/channel\/UCEPtRdzn0nqkij0s3IkKU0g"]},{"@type":"Person","@id":"https:\/\/apartamentselsllacs.com\/fr\/#\/schema\/person\/aed34ab05a7f0812d0dcebbe46f43ea5","name":"elsllacs","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/apartamentselsllacs.com\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e415adb15139330767a4113d338422f1fe2f1a98bb8c2c7d1a1a213bc5005cc8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e415adb15139330767a4113d338422f1fe2f1a98bb8c2c7d1a1a213bc5005cc8?s=96&d=mm&r=g","caption":"elsllacs"},"sameAs":["https:\/\/apartamentselsllacs.com"]}]}},"loftoceanMetas":{"authorName":"elsllacs","categories":[{"name":"\u00e9v\u00e9nements en Andorre","link":"https:\/\/apartamentselsllacs.com\/fr\/category\/evenements-en-andorre\/","count":28},{"name":"ski et sports d'hiver","link":"https:\/\/apartamentselsllacs.com\/fr\/category\/ski-et-sports-dhiver\/","count":51}],"date":"2 de f\u00e9vrier de 2022","featuredImageSRC":"https:\/\/apartamentselsllacs.com\/wp-content\/uploads\/2022\/02\/Finales-Copa-Europa-150x150.jpg"},"_links":{"self":[{"href":"https:\/\/apartamentselsllacs.com\/fr\/wp-json\/wp\/v2\/posts\/4441","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/apartamentselsllacs.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/apartamentselsllacs.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/apartamentselsllacs.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/apartamentselsllacs.com\/fr\/wp-json\/wp\/v2\/comments?post=4441"}],"version-history":[{"count":0,"href":"https:\/\/apartamentselsllacs.com\/fr\/wp-json\/wp\/v2\/posts\/4441\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/apartamentselsllacs.com\/fr\/wp-json\/wp\/v2\/media\/3313"}],"wp:attachment":[{"href":"https:\/\/apartamentselsllacs.com\/fr\/wp-json\/wp\/v2\/media?parent=4441"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/apartamentselsllacs.com\/fr\/wp-json\/wp\/v2\/categories?post=4441"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/apartamentselsllacs.com\/fr\/wp-json\/wp\/v2\/tags?post=4441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}